{"id":4047,"date":"2024-03-18T11:18:14","date_gmt":"2024-03-18T11:18:14","guid":{"rendered":"https:\/\/branddex.klinikadev.pl\/?post_type=product&#038;p=4047"},"modified":"2024-08-28T05:29:29","modified_gmt":"2024-08-28T05:29:29","slug":"palstop-pax-fittings","status":"publish","type":"product","link":"https:\/\/www.branddex.com\/en\/produkt\/palstop-pax-fittings\/","title":{"rendered":"Palstop\u00ae PAX &#8211; fire protection moldings"},"content":{"rendered":"<div id=\"block_4da70a9b90b111051fc29cc2bf39e67a\" class=\"b-image-text alignfull l-block\">\n  \n  \n    <div class=\"container\">\n                    <div class=\"row align-items-center justify-content-center\">\n                <div class=\"col-lg-6 order-2 order-lg-1\">\n                    <div class=\"b-image-text__text pl-20 mt-4 mt-lg-\">\n                        <div class=\"c-section-title left-border mb-40\">\n                                                            <span class=\"title-tag\">COOLING FIRE PROTECTION MOLDINGS<\/span>\n                                                                                        <h2>Palstop\u00ae PAX<\/h2>\n                                                    <\/div>\n                                                    <p><strong>Intended use<\/strong><\/p>\n<p>Palstop\u00ae PAX &#8211; fire protection moldings&nbsp; cool and insulate thermally in the event of fire. They are intended for use in fire rated constructions (e. g. glazing systems like fire windows and fire doors). In this way, higher fire resistance classes are achieved.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Tailored to your needs <\/strong><\/p>\n<p>Palstop\u00ae PAX &#8211; moldings&nbsp; are prepared to your requirements and delivered &#8220;Ready to Go&#8221;. You don&#8217;t have to worry about anything else. Our fire protection moldings can be produced with chamfers, folds, grooves and in different lengths and thicknesses. They can be packed in cardboard, wooden boxes or shrink-wrap. The choice is yours.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n                                            <\/div>\n                <\/div>\n                <div class=\"col-lg-6 order-1 order-lg-2\">\n                                            <div class=\"b-image-text__img\">\n                            <a href=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/fire-protection-moldings-main-img-en-v1.webp\" class=\"popup-link\">                                <noscript><img decoding=\"async\" src=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/fire-protection-moldings-main-img-en-v1.webp\" alt class=\"img-fluid\"><\/noscript><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" alt class=\"img-fluid lazyload\" data-src=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/fire-protection-moldings-main-img-en-v1.webp\">\n                            <\/a>                        <\/div>\n                                    <\/div>\n            <\/div>\n            <\/div>\n\n<style>#block_4da70a9b90b111051fc29cc2bf39e67a { padding-top: 32px;  } @media (min-width: 768px) { #block_4da70a9b90b111051fc29cc2bf39e67a { padding-top: 48px;  }} @media (min-width: 992px) { #block_4da70a9b90b111051fc29cc2bf39e67a { padding-top: 64px;  }} @media (min-width: 1200px) { #block_4da70a9b90b111051fc29cc2bf39e67a { padding-top: 72px;  }} @media (min-width: 1500px) { #block_4da70a9b90b111051fc29cc2bf39e67a { padding-top: 80px;  }} <\/style><\/div>\n\n\n      <div id=\"block_e7ee6d0855692e88460f78c822baceb3\" class=\"b-product-features alignfull l-block\">\n  \n  \n    <div class=\"b-product-features__content\">\n        <div class=\"container\">\n            <div class=\"row justify-content-center\">\n                <div class=\"col-xl-6 text-center\">\n                    <div class=\"c-section-title mb-40\">\n                                                    <span class=\"title-tag title-tag--secondary\">Palstop\u00ae PAX &#8211; fire protection moldings<\/span>\n                                                                            <h2 class=\"mb-0\">Technical data<\/h2>\n                                            <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"row justify-content-center b-product-features__elements mt-50\">\n                                                            <div class=\"col-xl-4 col-lg-6\">\n                            <div class=\"b-product-features__element\">\n                                                                    <div class=\"b-product-features__icon\">\n                                        <noscript><img decoding=\"async\" src=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/silne-chlodzenie.svg\" alt><\/noscript><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" alt data-src=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/silne-chlodzenie.svg\" class=\" lazyload\">\n                                    <\/div>\n                                                                <div class=\"b-product-features__texts\">\n                                                                            <div class=\"b-product-features__title\">\n                                            <h4>POWERFUL COOLING <\/h4>\n                                        <\/div>\n                                                                                                                <div class=\"b-product-features__text p-reset\">\n                                            <p>Powerful cooling in case of fire<\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                            <div class=\"col-xl-4 col-lg-6\">\n                            <div class=\"b-product-features__element\">\n                                                                    <div class=\"b-product-features__icon\">\n                                        <noscript><img decoding=\"async\" src=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/duza-wytrzymalosc.svg\" alt><\/noscript><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" alt data-src=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/duza-wytrzymalosc.svg\" class=\" lazyload\">\n                                    <\/div>\n                                                                <div class=\"b-product-features__texts\">\n                                                                            <div class=\"b-product-features__title\">\n                                            <h4>HIGH DURABILITY<\/h4>\n                                        <\/div>\n                                                                                                                <div class=\"b-product-features__text p-reset\">\n                                            <p>Thanks to reinforcement with glass mat<\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                            <div class=\"col-xl-4 col-lg-6\">\n                            <div class=\"b-product-features__element\">\n                                                                    <div class=\"b-product-features__icon\">\n                                        <noscript><img decoding=\"async\" src=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/termiczna-izolacja.svg\" alt><\/noscript><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" alt data-src=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/termiczna-izolacja.svg\" class=\" lazyload\">\n                                    <\/div>\n                                                                <div class=\"b-product-features__texts\">\n                                                                            <div class=\"b-product-features__title\">\n                                            <h4>THERMAL INSULATION<\/h4>\n                                        <\/div>\n                                                                                                                <div class=\"b-product-features__text p-reset\">\n                                            <p>Excellent thermal insulation<\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                            <div class=\"col-xl-4 col-lg-6\">\n                            <div class=\"b-product-features__element\">\n                                                                    <div class=\"b-product-features__icon\">\n                                        <noscript><img decoding=\"async\" src=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/dostosowywanie.svg\" alt><\/noscript><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" alt data-src=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/dostosowywanie.svg\" class=\" lazyload\">\n                                    <\/div>\n                                                                <div class=\"b-product-features__texts\">\n                                                                            <div class=\"b-product-features__title\">\n                                            <h4>CUSTOMIZATION<\/h4>\n                                        <\/div>\n                                                                                                                <div class=\"b-product-features__text p-reset\">\n                                            <p>Adaptations to technical requirements<\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                            <div class=\"col-xl-4 col-lg-6\">\n                            <div class=\"b-product-features__element\">\n                                                                    <div class=\"b-product-features__icon\">\n                                        <noscript><img decoding=\"async\" src=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/05\/odpornosc-na-wilgoc.svg\" alt><\/noscript><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" alt data-src=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/05\/odpornosc-na-wilgoc.svg\" class=\" lazyload\">\n                                    <\/div>\n                                                                <div class=\"b-product-features__texts\">\n                                                                            <div class=\"b-product-features__title\">\n                                            <h4>RESISTANCE TO MOISTURE<\/h4>\n                                        <\/div>\n                                                                                                                <div class=\"b-product-features__text p-reset\">\n                                            <p>Resistance to moisture<\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                            <div class=\"col-xl-4 col-lg-6\">\n                            <div class=\"b-product-features__element\">\n                                                                    <div class=\"b-product-features__icon\">\n                                        <noscript><img decoding=\"async\" src=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/nietoksyczne.svg\" alt><\/noscript><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" alt data-src=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/nietoksyczne.svg\" class=\" lazyload\">\n                                    <\/div>\n                                                                <div class=\"b-product-features__texts\">\n                                                                            <div class=\"b-product-features__title\">\n                                            <h4>NON-TOXIC <\/h4>\n                                        <\/div>\n                                                                                                                <div class=\"b-product-features__text p-reset\">\n                                            <p>No toxic substances contained<\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                                <\/div>\n        <\/div>\n    <\/div>\n\n<\/div>\n\n\n      <div id=\"block_bb49bbc328856c5c4a4eebbec821d796\" class=\"b-download alignfull l-block\">\n  \n  \n    <div class=\"b-download__inner\">\n        <div class=\"container\">\n            <div class=\"b-download__content\">\n                                                            <div class=\"b-download__element\">\n                            <div class=\"row d-flex align-items-center\">\n                                <div class=\"col-xl-9\">\n                                                                            <h4 class=\"b-download__title\">\n                                            Product catalogue                                        <\/h4>\n                                                                                                                <div class=\"b-download__description p-reset\">\n                                            <p>Check out our product catalogue.<\/p>\n                                        <\/div>\n                                                                    <\/div>\n                                <div class=\"col-xl-3\">\n                                                                            <div class=\"b-download__button text-end mt-4 mt-lg-0\">\n                                            <a href=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/08\/branddex_folder_EN_v16_tresc_mobile.pdf\" target=\"_blank\" class=\"c-btn c-btn--primary\" download>\n                                                <i class=\"far fa-file-download\"><\/i>Download File                                            <\/a>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                            <div class=\"b-download__element\">\n                            <div class=\"row d-flex align-items-center\">\n                                <div class=\"col-xl-9\">\n                                                                            <h4 class=\"b-download__title\">\n                                            Application instruction                                        <\/h4>\n                                                                                                                <div class=\"b-download__description p-reset\">\n                                            <p>Palstop Pax moldings<\/p>\n                                        <\/div>\n                                                                    <\/div>\n                                <div class=\"col-xl-3\">\n                                                                            <div class=\"b-download__button text-end mt-4 mt-lg-0\">\n                                            <a href=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/08\/PAX_EN_application-instruction.pdf\" target=\"_blank\" class=\"c-btn c-btn--primary\" download>\n                                                <i class=\"far fa-file-download\"><\/i>Download File                                            <\/a>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                                <\/div>\n        <\/div>\n    <\/div>\n\n<\/div>\n\n\n      <div id=\"block_9d7a45e20076b888c3c3c278e14398f0\" class=\"b-gallery skip-lazy alignfull l-block\">\n  \n  \n    <div class=\"b-gallery__inner\">\n        <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col-12\">\n                    <div class=\"b-gallery__images gallery\">\n                        <div class=\"row\">\n                                                                                                <div class=\"col-md-6 col-lg-4\">\n                                        <a href=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/palstop_pax_ksztaltka1_1.webp\" class=\"b-gallery__element\">\n                                            <img decoding=\"async\" src=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/palstop_pax_ksztaltka1_1-1024x768.webp\" alt class=\"img-fluid\">\n                                        <\/a>\n                                    <\/div>\n                                                                    <div class=\"col-md-6 col-lg-4\">\n                                        <a href=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/palstop_pax_ksztaltka1_2-.webp\" class=\"b-gallery__element\">\n                                            <img decoding=\"async\" src=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/palstop_pax_ksztaltka1_2--1024x768.webp\" alt class=\"img-fluid\">\n                                        <\/a>\n                                    <\/div>\n                                                                    <div class=\"col-md-6 col-lg-4\">\n                                        <a href=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/palstop_pax_ksztaltka1_3.webp\" class=\"b-gallery__element\">\n                                            <img decoding=\"async\" src=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/palstop_pax_ksztaltka1_3-1024x768.webp\" alt class=\"img-fluid\">\n                                        <\/a>\n                                    <\/div>\n                                                                    <div class=\"col-md-6 col-lg-4\">\n                                        <a href=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/palstop_pax_ksztaltka2_1.webp\" class=\"b-gallery__element\">\n                                            <img decoding=\"async\" src=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/palstop_pax_ksztaltka2_1-1024x768.webp\" alt class=\"img-fluid\">\n                                        <\/a>\n                                    <\/div>\n                                                                    <div class=\"col-md-6 col-lg-4\">\n                                        <a href=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/palstop_pax_ksztaltka2_3.webp\" class=\"b-gallery__element\">\n                                            <img decoding=\"async\" src=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/palstop_pax_ksztaltka2_3-1024x768.webp\" alt class=\"img-fluid\">\n                                        <\/a>\n                                    <\/div>\n                                                                    <div class=\"col-md-6 col-lg-4\">\n                                        <a href=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/palstop_pax_ksztaltka2_2.webp\" class=\"b-gallery__element\">\n                                            <img decoding=\"async\" src=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/palstop_pax_ksztaltka2_2-1024x768.webp\" alt class=\"img-fluid\">\n                                        <\/a>\n                                    <\/div>\n                                                                    <div class=\"col-md-6 col-lg-4\">\n                                        <a href=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/palstop_pax_ksztaltka3_1.webp\" class=\"b-gallery__element\">\n                                            <img decoding=\"async\" src=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/palstop_pax_ksztaltka3_1-1024x768.webp\" alt class=\"img-fluid\">\n                                        <\/a>\n                                    <\/div>\n                                                                    <div class=\"col-md-6 col-lg-4\">\n                                        <a href=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/palstop_pax_ksztaltka3_2.webp\" class=\"b-gallery__element\">\n                                            <img decoding=\"async\" src=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/palstop_pax_ksztaltka3_2-1024x768.webp\" alt class=\"img-fluid\">\n                                        <\/a>\n                                    <\/div>\n                                                                    <div class=\"col-md-6 col-lg-4\">\n                                        <a href=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/palstop_pax_ksztaltka3_3.webp\" class=\"b-gallery__element\">\n                                            <img decoding=\"async\" src=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/palstop_pax_ksztaltka3_3-1024x768.webp\" alt class=\"img-fluid\">\n                                        <\/a>\n                                    <\/div>\n                                                                    <div class=\"col-md-6 col-lg-4\">\n                                        <a href=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/palstop_pax_ksztaltka4_1.webp\" class=\"b-gallery__element\">\n                                            <img decoding=\"async\" src=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/palstop_pax_ksztaltka4_1-1024x768.webp\" alt class=\"img-fluid\">\n                                        <\/a>\n                                    <\/div>\n                                                                    <div class=\"col-md-6 col-lg-4\">\n                                        <a href=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/palstop_pax_ksztaltka4_2.webp\" class=\"b-gallery__element\">\n                                            <img decoding=\"async\" src=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/palstop_pax_ksztaltka4_2-1024x768.webp\" alt class=\"img-fluid\">\n                                        <\/a>\n                                    <\/div>\n                                                                    <div class=\"col-md-6 col-lg-4\">\n                                        <a href=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/palstop_pax_ksztaltka4_3.webp\" class=\"b-gallery__element\">\n                                            <img decoding=\"async\" src=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/palstop_pax_ksztaltka4_3-1024x768.webp\" alt class=\"img-fluid\">\n                                        <\/a>\n                                    <\/div>\n                                                                                    <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<\/div>\n\n\n      <div id=\"block_4acaf3e98d61ffdda0f59e9211220385\" class=\"b-cta alignfull lazyload bg-center bg-no-repeat bg-cover bg-scroll  l-block\" data-bg=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/cta-bg-1.webp\">\n  \n  \n    <section class=\"b-cta__inner cta-style-two pt-120 pb-120 skip-lazy\">\n        <div class=\"container\">\n            <div class=\"b-cta__content\">\n                                    <div class=\"b-cta__image skip-lazy\" data-aos=\"zoom-out-up\" data-aos-delay=\"100\" data-aos-duration=\"1000\" data-aos-once=\"true\">\n                        <img decoding=\"async\" src=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/cta-img-1.webp\" alt>\n                    <\/div>\n                                <div class=\"b-cta__text\">\n                    <div class=\"row align-items-center justify-content-end\">\n                        <div class=\"col-lg-6 col-md-5\">\n                            <div class=\"c-section-title left-border\">\n                                                                    <span class=\"title-tag\">Monday &#8211; Friday 7:00 &#8211; 15:00<\/span>\n                                                                                                    <h2>Contact sales department<\/h2>\n                                                            <\/div>\n                        <\/div>\n                        <div class=\"col-lg-3 col-md-4 text-end\">\n                                                            <a class=\"c-btn c-btn--white b-cta__btn\" href=\"tel:+48915772215\">\n                                    <i class=\"fal fa-phone-alt\"><\/i>\n                                    <span>+48 91 577 22 15<\/span>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/section>\n\n<style>#block_4acaf3e98d61ffdda0f59e9211220385 { background-color: #900d11;  } <\/style><\/div>\n\n\n<div class=\"wp-block-group alignfull\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n      <div id=\"block_096277dafec6c2fc204943caeabdf995\" class=\"b-contact-box alignfull l-block\">\n  \n  \n    <div class=\"container\">\n        <div class=\"b-contact-box__texts\">\n            <div class=\"row\">\n                <div class=\"col-lg-8\">\n                                            <div class=\"c-section-title left-border mb-40\">\n                            <h2>Write to us or call us<\/h2>\n                        <\/div>\n                                                                <div class=\"p-reset\">\n                            <p>If you are looking for fire protection products that boost the fire resistance of building structures (e.g. steel structures, walls, ceilings, electrical installations, ventilation ducts and cable trays), then contact us.<\/p>\n<p>Our specialists will be happy to advise you.<\/p>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n        <div class=\"b-contact-box__wrapper\">\n            <div class=\"row no-gutters align-items-center align-items-lg-center justify-content-center\">\n                <div class=\"col-lg-5\">\n                    <div class=\"b-contact-box__info-list\">\n                                                                                    <div class=\"info-box\">\n                                    <div class=\"info-box__icons\">\n                                                                                            <div class=\"info-box__icon\">\n                                                        <noscript><img decoding=\"async\" src=\"https:\/\/www.branddex.com\/wp-content\/themes\/branddex-theme\/assets\/img\/flags\/en-flag.svg\" alt=\"en\"><\/noscript><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" alt=\"en\" data-src=\"https:\/\/www.branddex.com\/wp-content\/themes\/branddex-theme\/assets\/img\/flags\/en-flag.svg\" class=\" lazyload\">\n                                                    <\/div>\n                                                                                                                                                <div class=\"info-box__icon\">\n                                                        <noscript><img decoding=\"async\" src=\"https:\/\/www.branddex.com\/wp-content\/themes\/branddex-theme\/assets\/img\/flags\/de-flag.svg\" alt=\"de\"><\/noscript><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" alt=\"de\" data-src=\"https:\/\/www.branddex.com\/wp-content\/themes\/branddex-theme\/assets\/img\/flags\/de-flag.svg\" class=\" lazyload\">\n                                                    <\/div>\n                                                                                                                                                <div class=\"info-box__icon\">\n                                                        <noscript><img decoding=\"async\" src=\"https:\/\/www.branddex.com\/wp-content\/themes\/branddex-theme\/assets\/img\/flags\/pl-flag.svg\" alt=\"pl\"><\/noscript><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" alt=\"pl\" data-src=\"https:\/\/www.branddex.com\/wp-content\/themes\/branddex-theme\/assets\/img\/flags\/pl-flag.svg\" class=\" lazyload\">\n                                                    <\/div>\n                                                                                                                                                                        <\/div>\n                                    <div class=\"info-box__content\">\n                                                                                    <h4>Ask our expert<\/h4>\n                                                                                                                            <span class=\"info-box__phone\">\n                                                <a href=\"+48915772215\">+48 915 772 215<\/a>\n                                            <\/span>\n                                                                                <span class=\"info-box__email\">\n                                                                                            <a href=\"mailto:branddex@branddex.pl\">branddex@branddex.pl<\/a>\n                                                                                    <\/span>\n                                    <\/div>\n                                <\/div>\n                                                                                                                                        <div class=\"info-box\">\n                                    <div class=\"info-box__icons\">\n                                                                            <\/div>\n                                    <div class=\"info-box__content\">\n                                                                                                                        <span class=\"info-box__email\">\n                                                                                    <\/span>\n                                    <\/div>\n                                <\/div>\n                                                                        <\/div>\n                <\/div>\n                <div class=\"col-lg-7\">\n                    <div class=\"b-contact-box__contact-form\">\n                                                    <!-- HTML Forms v1.3.34 - https:\/\/wordpress.org\/plugins\/html-forms\/ --><form method=\"post\" class=\"hf-form hf-form-4004 \" data-id=\"4004\" data-title=\"Contact Form EN\" data-slug=\"contact-form-en\" data-message-success=\"Thank you, your message has been sent.\" data-message-invalid-email=\"Sorry, that email address looks invalid.\" data-message-required-field-missing=\"Please fill in the required fields.\" data-message-error=\"Oops. An error occurred.\"><input type=\"hidden\" name=\"_hf_form_id\" value=\"4004\"><div style=\"display: none;\"><input type=\"text\" name=\"_hf_h4004\" value><\/div><div class=\"hf-fields-wrap\"><div class=\"contact-form__content\">\n    <div class=\"row padding-custom\">\n        <div class=\"col-12 col-lg-6\">\n            <div class=\"input-group mb-10\">\n                <div class=\"icon\">\n                    <i class=\"fal fa-user\"><\/i>\n                <\/div>\n                <input type=\"text\" name=\"NAME\" placeholder=\"Name and surname\" required>\n            <\/div>\n        <\/div>\n        <div class=\"col-12 col-lg-6\">\n            <div class=\"input-group mb-10\">\n                <div class=\"icon\">\n                    <i class=\"fal fa-envelope\"><\/i>\n                <\/div>\n                <input type=\"text\" name=\"EMAIL\" placeholder=\"E-mail\" required>\n            <\/div>\n        <\/div>\n        <div class=\"col-12 col-lg-6\">\n            <div class=\"input-group mb-10\">\n                <div class=\"icon\">\n                    <i class=\"fal fa-phone-alt\"><\/i>\n                <\/div>\n                <input type=\"text\" name=\"PHONE\" placeholder=\"Phone number\">\n            <\/div>\n        <\/div>\n        <div class=\"col-12 col-lg-6\">\n            <div class=\"input-group mb-10\">\n                <div class=\"icon\">\n                    <i class=\"fal fa-door-open\"><\/i>\n                <\/div>\n                <div class=\"custom-select\">\n                    <select name=\"PRODUCT\" id=\"select-product\">\n                        <option value=\"P\u0142yta Palstop PAX\">Palstop PAX board<\/option>\n                        <option value=\"P\u0142yta Palstop PAX H\">Palstop PAX H board<\/option>\n                        <option value=\"Kszta\u0142tki ogniochronne\">Fireproofing fittings<\/option>\n                        <option value=\"P\u0142yta Palstop P\">Palstop P board<\/option>\n                        <option value=\"Uszczelki Palstop P\">Palstop P seals<\/option>\n                        <option value=\"Inne\">Other<\/option>\n                    <\/select>\n                <\/div>\n            <\/div>\n        <\/div>\n        <div class=\"col-12\">\n            <div class=\"input-group textarea mb-10\">\n                <div class=\"icon\">\n                    <i class=\"fal fa-edit\"><\/i>\n                <\/div>\n                <textarea name=\"MESSAGE\" placeholder=\"Content of the message\"><\/textarea>\n            <\/div>\n        <\/div>\n        <div class=\"col-12\">\n            <div class=\"custom-checkbox\">\n                <input type=\"checkbox\" class=\"styled-checkbox\" name=\"PRIVACYPOLICY\" id=\"privacyPolicy\" value=\"Wyra\u017cam zgod\u0119 na przetwarzanie moich danych osobowych oraz akceptuj\u0119 polityk\u0119 prywatno\u015bci\" required>\n                <label for=\"privacyPolicy\"><span>I agree to the processing of my personal data and accept the <a href=\"\/polityka-prywatnosci\/\" target=\"_blank\">Privacy Policy<\/a><\/span><\/label>\n            <\/div>\n        <\/div>\n        <div class=\"col-12 text-center\">\n            <button type=\"submit\" class=\"c-btn c-btn--primary\">SEND A MESSAGE<\/button>\n        <\/div>\n    <\/div>\n<\/div><noscript>Please enable JavaScript for this form to work.<\/noscript><\/div><\/form><!-- \/ HTML Forms -->                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cools and insulates thermally in the event of fire. Used in construction elements to achieve a higher fire resistance class.<\/p>\n","protected":false},"author":2,"featured_media":2047,"template":"","meta":{"_acf_changed":false,"footnotes":""},"product_type":[35],"class_list":["post-4047","product","type-product","status-publish","has-post-thumbnail","","product_type-cooling-fire-protection-products"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Palstop\u00ae PAX - fire protection moldings - Branddex<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.branddex.com\/en\/produkt\/palstop-pax-fittings\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Palstop\u00ae PAX - fire protection moldings - Branddex\" \/>\n<meta property=\"og:description\" content=\"Cools and insulates thermally in the event of fire. Used in construction elements to achieve a higher fire resistance class.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.branddex.com\/en\/produkt\/palstop-pax-fittings\/\" \/>\n<meta property=\"og:site_name\" content=\"Branddex\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-28T05:29:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/ksztaltki-ogniochronne-box.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"811\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.branddex.com\/en\/produkt\/palstop-pax-fittings\/\",\"url\":\"https:\/\/www.branddex.com\/en\/produkt\/palstop-pax-fittings\/\",\"name\":\"Palstop\u00ae PAX - fire protection moldings - Branddex\",\"isPartOf\":{\"@id\":\"https:\/\/www.branddex.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.branddex.com\/en\/produkt\/palstop-pax-fittings\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.branddex.com\/en\/produkt\/palstop-pax-fittings\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/ksztaltki-ogniochronne-box.webp\",\"datePublished\":\"2024-03-18T11:18:14+00:00\",\"dateModified\":\"2024-08-28T05:29:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.branddex.com\/en\/produkt\/palstop-pax-fittings\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.branddex.com\/en\/produkt\/palstop-pax-fittings\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.branddex.com\/en\/produkt\/palstop-pax-fittings\/#primaryimage\",\"url\":\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/ksztaltki-ogniochronne-box.webp\",\"contentUrl\":\"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/ksztaltki-ogniochronne-box.webp\",\"width\":1000,\"height\":811},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.branddex.com\/en\/produkt\/palstop-pax-fittings\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.branddex.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Palstop\u00ae PAX &#8211; fire protection moldings\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.branddex.com\/en\/#website\",\"url\":\"https:\/\/www.branddex.com\/en\/\",\"name\":\"Branddex\",\"description\":\"Ch\u0142odz\u0105ce i p\u0119czniej\u0105ce materia\u0142y ogniochronne\",\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Palstop\u00ae PAX - fire protection moldings - Branddex","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.branddex.com\/en\/produkt\/palstop-pax-fittings\/","og_locale":"en_US","og_type":"article","og_title":"Palstop\u00ae PAX - fire protection moldings - Branddex","og_description":"Cools and insulates thermally in the event of fire. Used in construction elements to achieve a higher fire resistance class.","og_url":"https:\/\/www.branddex.com\/en\/produkt\/palstop-pax-fittings\/","og_site_name":"Branddex","article_modified_time":"2024-08-28T05:29:29+00:00","og_image":[{"width":1000,"height":811,"url":"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/ksztaltki-ogniochronne-box.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.branddex.com\/en\/produkt\/palstop-pax-fittings\/","url":"https:\/\/www.branddex.com\/en\/produkt\/palstop-pax-fittings\/","name":"Palstop\u00ae PAX - fire protection moldings - Branddex","isPartOf":{"@id":"https:\/\/www.branddex.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.branddex.com\/en\/produkt\/palstop-pax-fittings\/#primaryimage"},"image":{"@id":"https:\/\/www.branddex.com\/en\/produkt\/palstop-pax-fittings\/#primaryimage"},"thumbnailUrl":"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/ksztaltki-ogniochronne-box.webp","datePublished":"2024-03-18T11:18:14+00:00","dateModified":"2024-08-28T05:29:29+00:00","breadcrumb":{"@id":"https:\/\/www.branddex.com\/en\/produkt\/palstop-pax-fittings\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.branddex.com\/en\/produkt\/palstop-pax-fittings\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.branddex.com\/en\/produkt\/palstop-pax-fittings\/#primaryimage","url":"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/ksztaltki-ogniochronne-box.webp","contentUrl":"https:\/\/www.branddex.com\/wp-content\/uploads\/2024\/03\/ksztaltki-ogniochronne-box.webp","width":1000,"height":811},{"@type":"BreadcrumbList","@id":"https:\/\/www.branddex.com\/en\/produkt\/palstop-pax-fittings\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.branddex.com\/en\/"},{"@type":"ListItem","position":2,"name":"Palstop\u00ae PAX &#8211; fire protection moldings"}]},{"@type":"WebSite","@id":"https:\/\/www.branddex.com\/en\/#website","url":"https:\/\/www.branddex.com\/en\/","name":"Branddex","description":"Ch\u0142odz\u0105ce i p\u0119czniej\u0105ce materia\u0142y ogniochronne","inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.branddex.com\/en\/wp-json\/wp\/v2\/product\/4047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.branddex.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.branddex.com\/en\/wp-json\/wp\/v2\/types\/product"}],"author":[{"embeddable":true,"href":"https:\/\/www.branddex.com\/en\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":24,"href":"https:\/\/www.branddex.com\/en\/wp-json\/wp\/v2\/product\/4047\/revisions"}],"predecessor-version":[{"id":5349,"href":"https:\/\/www.branddex.com\/en\/wp-json\/wp\/v2\/product\/4047\/revisions\/5349"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.branddex.com\/en\/wp-json\/wp\/v2\/media\/2047"}],"wp:attachment":[{"href":"https:\/\/www.branddex.com\/en\/wp-json\/wp\/v2\/media?parent=4047"}],"wp:term":[{"taxonomy":"product_type","embeddable":true,"href":"https:\/\/www.branddex.com\/en\/wp-json\/wp\/v2\/product_type?post=4047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}